{"id":2551,"date":"2007-10-16T16:16:00","date_gmt":"2007-10-16T16:16:00","guid":{"rendered":"http:\/\/www.yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map.html"},"modified":"2007-10-16T16:16:00","modified_gmt":"2007-10-16T16:16:00","slug":"penn-state-at-indiana-coverage-map","status":"publish","type":"post","link":"https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/","title":{"rendered":"Penn State at Indiana coverage map"},"content":{"rendered":"<p>ESPN, Saturday at noon. Areas getting the game are in blue.<\/p>\n<p><a onblur=\"try {parent.deselectBloggerImageGracefully();} catch(e) {}\" href=\"https:\/\/i0.wp.com\/www.yurasko.net\/wfy\/uploaded_images\/pennstatevsindianacoveragem-795750.gif\"><img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" style=\"display:block; margin:0px auto 10px; text-align:center;cursor:pointer; cursor:hand;\" src=\"https:\/\/i0.wp.com\/www.yurasko.net\/wfy\/uploaded_images\/pennstatevsindianacoveragem-795745.gif\" border=\"0\" alt=\"\" \/><\/a><\/p>\n<p>Source: <a href=\"http:\/\/live.psu.edu\/index.php?sec=vs_highlight&#038;story=26586&#038;highlight=1\"><span style=\"font-weight:bold;\">Penn State Live<\/span><\/a><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"\/website_3c1e0e40\/graphics\/technorati.gif\" border=\"0\">  <a href=\"http:\/\/www.technorati.com\/tag\/PennState\" rel=\"tag\">Penn State<\/a>, <a href=\"http:\/\/www.technorati.com\/tag\/ABC\" rel=\"tag\">ABC<\/a>, <a href=\"http:\/\/www.technorati.com\/tag\/coveragemap\" rel=\"tag\">coverage map<\/a>, <a href=\"http:\/\/www.technorati.com\/tag\/football\" rel=\"tag\">football<\/a><\/p>\n<div class=\"blogger-post-footer\">&copy;MMX William F. Yurasko<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ESPN, Saturday at noon. Areas getting the game are in blue. Source: Penn State Live Penn State, ABC, coverage map, football &copy;MMX William F. Yurasko<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[76],"tags":[267,823,1352,1382],"class_list":["post-2551","post","type-post","status-publish","format-standard","hentry","category-psu-football-2007","tag-big-ten","tag-indiana-hoosiers","tag-penn-state","tag-penn-state-vs-indiana-2007"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Penn State at Indiana coverage map - Blog - William F. Yurasko<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Penn State at Indiana coverage map - Blog - William F. Yurasko\" \/>\n<meta property=\"og:description\" content=\"ESPN, Saturday at noon. Areas getting the game are in blue. Source: Penn State Live Penn State, ABC, coverage map, football &copy;MMX William F. Yurasko\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - William F. Yurasko\" \/>\n<meta property=\"article:published_time\" content=\"2007-10-16T16:16:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.yurasko.net\/wfy\/uploaded_images\/pennstatevsindianacoveragem-795745.gif\" \/>\n<meta name=\"author\" content=\"wfyurasko\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"wfyurasko\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/2007\\\/10\\\/penn-state-at-indiana-coverage-map\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/2007\\\/10\\\/penn-state-at-indiana-coverage-map\\\/\"},\"author\":{\"name\":\"wfyurasko\",\"@id\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/#\\\/schema\\\/person\\\/ac8cc411e132f659e3520b7aaf758773\"},\"headline\":\"Penn State at Indiana coverage map\",\"datePublished\":\"2007-10-16T16:16:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/2007\\\/10\\\/penn-state-at-indiana-coverage-map\\\/\"},\"wordCount\":32,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/2007\\\/10\\\/penn-state-at-indiana-coverage-map\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.yurasko.net\\\/wfy\\\/uploaded_images\\\/pennstatevsindianacoveragem-795745.gif\",\"keywords\":[\"Big Ten\",\"Indiana Hoosiers\",\"Penn State\",\"Penn State vs. Indiana 2007\"],\"articleSection\":[\"PSU Football 2007\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/yurasko.net\\\/wfy\\\/2007\\\/10\\\/penn-state-at-indiana-coverage-map\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/2007\\\/10\\\/penn-state-at-indiana-coverage-map\\\/\",\"url\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/2007\\\/10\\\/penn-state-at-indiana-coverage-map\\\/\",\"name\":\"Penn State at Indiana coverage map - Blog - William F. Yurasko\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/2007\\\/10\\\/penn-state-at-indiana-coverage-map\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/2007\\\/10\\\/penn-state-at-indiana-coverage-map\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.yurasko.net\\\/wfy\\\/uploaded_images\\\/pennstatevsindianacoveragem-795745.gif\",\"datePublished\":\"2007-10-16T16:16:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/#\\\/schema\\\/person\\\/ac8cc411e132f659e3520b7aaf758773\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/2007\\\/10\\\/penn-state-at-indiana-coverage-map\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/yurasko.net\\\/wfy\\\/2007\\\/10\\\/penn-state-at-indiana-coverage-map\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/2007\\\/10\\\/penn-state-at-indiana-coverage-map\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.yurasko.net\\\/wfy\\\/uploaded_images\\\/pennstatevsindianacoveragem-795745.gif\",\"contentUrl\":\"http:\\\/\\\/www.yurasko.net\\\/wfy\\\/uploaded_images\\\/pennstatevsindianacoveragem-795745.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/2007\\\/10\\\/penn-state-at-indiana-coverage-map\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Penn State at Indiana coverage map\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/#website\",\"url\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/\",\"name\":\"Blog - William F. Yurasko\",\"description\":\"Yet another Washingtonian pushing the ubiquitous Nats\\\/DC sports, Penn State, commuting, bicycling, kayaking, broomball, skiing, gin &amp; tonic agenda.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/#\\\/schema\\\/person\\\/ac8cc411e132f659e3520b7aaf758773\",\"name\":\"wfyurasko\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d848f90a00e30a5618468b70a0cf9639ad6175f078f9417858cef279ef96fe26?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d848f90a00e30a5618468b70a0cf9639ad6175f078f9417858cef279ef96fe26?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d848f90a00e30a5618468b70a0cf9639ad6175f078f9417858cef279ef96fe26?s=96&d=mm&r=g\",\"caption\":\"wfyurasko\"},\"sameAs\":[\"https:\\\/\\\/jus.tia.mybluehost.me\\\/website_3c1e0e40\"],\"url\":\"https:\\\/\\\/yurasko.net\\\/wfy\\\/author\\\/wfyurasko\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Penn State at Indiana coverage map - Blog - William F. Yurasko","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/","og_locale":"en_US","og_type":"article","og_title":"Penn State at Indiana coverage map - Blog - William F. Yurasko","og_description":"ESPN, Saturday at noon. Areas getting the game are in blue. Source: Penn State Live Penn State, ABC, coverage map, football &copy;MMX William F. Yurasko","og_url":"https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/","og_site_name":"Blog - William F. Yurasko","article_published_time":"2007-10-16T16:16:00+00:00","og_image":[{"url":"http:\/\/www.yurasko.net\/wfy\/uploaded_images\/pennstatevsindianacoveragem-795745.gif","type":"","width":"","height":""}],"author":"wfyurasko","twitter_card":"summary_large_image","twitter_misc":{"Written by":"wfyurasko"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/#article","isPartOf":{"@id":"https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/"},"author":{"name":"wfyurasko","@id":"https:\/\/yurasko.net\/wfy\/#\/schema\/person\/ac8cc411e132f659e3520b7aaf758773"},"headline":"Penn State at Indiana coverage map","datePublished":"2007-10-16T16:16:00+00:00","mainEntityOfPage":{"@id":"https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/"},"wordCount":32,"commentCount":0,"image":{"@id":"https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/#primaryimage"},"thumbnailUrl":"http:\/\/www.yurasko.net\/wfy\/uploaded_images\/pennstatevsindianacoveragem-795745.gif","keywords":["Big Ten","Indiana Hoosiers","Penn State","Penn State vs. Indiana 2007"],"articleSection":["PSU Football 2007"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/","url":"https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/","name":"Penn State at Indiana coverage map - Blog - William F. Yurasko","isPartOf":{"@id":"https:\/\/yurasko.net\/wfy\/#website"},"primaryImageOfPage":{"@id":"https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/#primaryimage"},"image":{"@id":"https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/#primaryimage"},"thumbnailUrl":"http:\/\/www.yurasko.net\/wfy\/uploaded_images\/pennstatevsindianacoveragem-795745.gif","datePublished":"2007-10-16T16:16:00+00:00","author":{"@id":"https:\/\/yurasko.net\/wfy\/#\/schema\/person\/ac8cc411e132f659e3520b7aaf758773"},"breadcrumb":{"@id":"https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/#primaryimage","url":"http:\/\/www.yurasko.net\/wfy\/uploaded_images\/pennstatevsindianacoveragem-795745.gif","contentUrl":"http:\/\/www.yurasko.net\/wfy\/uploaded_images\/pennstatevsindianacoveragem-795745.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/yurasko.net\/wfy\/2007\/10\/penn-state-at-indiana-coverage-map\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/yurasko.net\/wfy\/"},{"@type":"ListItem","position":2,"name":"Penn State at Indiana coverage map"}]},{"@type":"WebSite","@id":"https:\/\/yurasko.net\/wfy\/#website","url":"https:\/\/yurasko.net\/wfy\/","name":"Blog - William F. Yurasko","description":"Yet another Washingtonian pushing the ubiquitous Nats\/DC sports, Penn State, commuting, bicycling, kayaking, broomball, skiing, gin &amp; tonic agenda.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yurasko.net\/wfy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/yurasko.net\/wfy\/#\/schema\/person\/ac8cc411e132f659e3520b7aaf758773","name":"wfyurasko","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d848f90a00e30a5618468b70a0cf9639ad6175f078f9417858cef279ef96fe26?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d848f90a00e30a5618468b70a0cf9639ad6175f078f9417858cef279ef96fe26?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d848f90a00e30a5618468b70a0cf9639ad6175f078f9417858cef279ef96fe26?s=96&d=mm&r=g","caption":"wfyurasko"},"sameAs":["https:\/\/jus.tia.mybluehost.me\/website_3c1e0e40"],"url":"https:\/\/yurasko.net\/wfy\/author\/wfyurasko\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/yurasko.net\/wfy\/wp-json\/wp\/v2\/posts\/2551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yurasko.net\/wfy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yurasko.net\/wfy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yurasko.net\/wfy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/yurasko.net\/wfy\/wp-json\/wp\/v2\/comments?post=2551"}],"version-history":[{"count":0,"href":"https:\/\/yurasko.net\/wfy\/wp-json\/wp\/v2\/posts\/2551\/revisions"}],"wp:attachment":[{"href":"https:\/\/yurasko.net\/wfy\/wp-json\/wp\/v2\/media?parent=2551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yurasko.net\/wfy\/wp-json\/wp\/v2\/categories?post=2551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yurasko.net\/wfy\/wp-json\/wp\/v2\/tags?post=2551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}